{"id":3056,"date":"2023-03-10T11:03:20","date_gmt":"2023-03-10T11:03:20","guid":{"rendered":"https:\/\/lexcrea.com\/?p=3056"},"modified":"2025-07-28T07:52:23","modified_gmt":"2025-07-28T07:52:23","slug":"la-evolucion-y-impacto-de-easo-ventures-en-el-pais-vasco","status":"publish","type":"post","link":"https:\/\/lexcrea.com\/en\/la-evolucion-y-impacto-de-easo-ventures-en-el-pais-vasco\/","title":{"rendered":"La evoluci\u00f3n y el impacto de EASO Ventures en el Pa\u00eds Vasco de la mano de Pedro Mu\u00f1oz-Baroja"},"content":{"rendered":"<p>Desde <a href=\"http:\/\/www.lexcrea.com\/podcast\">The Law Podcast For New Ventures<\/a> by Lexcrea cada mes te presentamos a dos personas relevantes de todo el ecosistema emprendedor.<\/p>\n\n\n\n<p>En este episodio, <a href=\"https:\/\/lexcrea.com\/equipo\/silvia-martinez-losas\/\">Silvia<\/a> tuvo el placer de hablar con Pedro Mu\u00f1oz-Baroja, el Managing Partner y uno de los fundadores, junto a Jose Poza y Juan Mari Ochoa, de <a href=\"https:\/\/www.easoventures.com\/\" rel=\"nofollow noopener\" target=\"_blank\">EASO Ventures<\/a>. EASO es la primera Sociedad de Capital Riesgo Vasca y Privada que nace con el fin de acompa\u00f1ar a startups y Pymes.<\/p>\n\n\n\n<p>Pedro fue el promotor de lo que hoy conocemos como el ecosistema startup en el Pa\u00eds Vasco a trav\u00e9s de <a href=\"https:\/\/www.berriup.com\/\" data-type=\"link\" data-id=\"https:\/\/www.berriup.com\/\" rel=\"nofollow noopener\" target=\"_blank\">BerriUp<\/a>, la primera aceleradora de startups en la regi\u00f3n que le llev\u00f3 al inevitable segundo paso, la creaci\u00f3n de EASO que hoy ya cuenta con su segundo.<\/p>\n\n\n\n<p>\u00bfCu\u00e1l es el reto m\u00e1s grande qu\u00e9 se han encontrado en el Pa\u00eds Vasco cuando se trata de talento e inversi\u00f3n en el mismo?<\/p>\n\n\n\n<p>\u00bfQu\u00e9 proyectos est\u00e1n buscando y en cuantas empresas m\u00e1s est\u00e1n buscando invertir desde EASO?<\/p>\n\n\n\n<p>\u00bfCu\u00e1l es el pr\u00f3ximo paso para EASO? Hablamos sobre la primera gestora Vasca, Stellum Growth, impulsada por Pedro, como dice el mismo, una evoluci\u00f3n natural, adem\u00e1s aprovechamos pedirle alg\u00fan que otro consejo para los emprendedores.<\/p>\n\n\n\n<iframe src=\"https:\/\/www.ivoox.com\/player_ej_104372662_6_1.html?c1=d44434\" width=\"100%\" height=\"200\" frameborder=\"0\" allowfullscreen=\"\" scrolling=\"no\" loading=\"lazy\"><\/iframe>","protected":false},"excerpt":{"rendered":"<p>Desde The Law Podcast For New Ventures by Lexcrea cada mes te presentamos a dos personas relevantes de todo el <a class=\"read_more\" href=\"https:\/\/lexcrea.com\/en\/la-evolucion-y-impacto-de-easo-ventures-en-el-pais-vasco\/\" target=\"_blank\" style=\"font-weight: 700;\">&#8230; LEER M\u00c1S<\/a><\/p>","protected":false},"author":6,"featured_media":3059,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[2666],"tags":[],"class_list":["post-3056","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-podcasts","wpautop"],"jetpack_featured_media_url":"https:\/\/lexcrea.com\/wp-content\/uploads\/2023\/03\/La-evolucion-y-el-impacto-de-EASO-Ventures-en-el-Pais-Vasco-con-Pedro-Munoz-Baroja-1.png","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/lexcrea.com\/en\/wp-json\/wp\/v2\/posts\/3056","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/lexcrea.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/lexcrea.com\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/lexcrea.com\/en\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/lexcrea.com\/en\/wp-json\/wp\/v2\/comments?post=3056"}],"version-history":[{"count":2,"href":"https:\/\/lexcrea.com\/en\/wp-json\/wp\/v2\/posts\/3056\/revisions"}],"predecessor-version":[{"id":3665,"href":"https:\/\/lexcrea.com\/en\/wp-json\/wp\/v2\/posts\/3056\/revisions\/3665"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/lexcrea.com\/en\/wp-json\/wp\/v2\/media\/3059"}],"wp:attachment":[{"href":"https:\/\/lexcrea.com\/en\/wp-json\/wp\/v2\/media?parent=3056"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/lexcrea.com\/en\/wp-json\/wp\/v2\/categories?post=3056"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/lexcrea.com\/en\/wp-json\/wp\/v2\/tags?post=3056"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}